{"id":282,"date":"2021-06-23T15:15:15","date_gmt":"2021-06-23T13:15:15","guid":{"rendered":"https:\/\/businesscoachingonline.de\/?page_id=282"},"modified":"2025-10-25T12:30:02","modified_gmt":"2025-10-25T10:30:02","slug":"about-me","status":"publish","type":"page","link":"https:\/\/businesscoachingonline.de\/en\/about-me\/","title":{"rendered":"About me"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;522&#8243; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;skip-lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;16%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;16%&#8221; left_padding_desktop=&#8221;9%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;9%&#8221; top_padding_tablet=&#8221;25%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;25%&#8221; top_padding_phone=&#8221;35%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;35%&#8221; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#000000&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;radial&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;45%&#8221; bg_image_animation=&#8221;zoom-out&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;center&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;radial&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-reveal&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; zindex=&#8221;20&#8243; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#ffffff&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;ABOUT ME&#8221; font_size=&#8221;9vh&#8221; animation_delay=&#8221;200&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1761388141006{margin-bottom: 0px !important;padding-bottom: 15px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h2>ANDREAS KLARE &#8211; BUSINESS COACH WITH INTERNATIONAL LEADERSHIP BACKGROUND<\/h2>\n<p><span style=\"font-size: 14pt;\">With more than 25 years of international professional and leadership experience in various operational and strategic roles in Germany and abroad, I know how difficult it is to constantly drive the own career and to regularly adapt to new work environments without neglecting family and friends &#8211; as well as the own health.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Looking back, I am quite satisfied &#8211; and admittedly also a bit proud &#8211; of what I have achieved so far. However, if I had a good coach by my side from time to time, some career decisions would certainly have turned out differently and stress phases might have been shorter or less intense (in the sense of &#8220;working smarter, not harder&#8221;).<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">I became a business coach and mentor not only because of this realization, but also because I enjoy the development of people and like to share my experience with others. I am doing this in a manner of openness, creativity, respect and empathy. In addition, I am a fundamentally positive person who likes to laugh and make people laugh.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">The matrix organization of an international logistics group gave me the chance to develop both vertically (&#8220;climbing the career ladder&#8221;) and horizontally. I assumed functions that were in part very different but complemented well and built on each other in a conclusive way \u2013 comprising all operational business units of the company as well as Sales and Finance:<\/span>[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-chevron-right\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"5px\" data-alignment=\"left\"> \n<ul>\n<li><span style=\"font-size: 14pt;\">Marketing, sales and key account management<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Customer service<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Implementation of new business<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Product and market development, strategic planning<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Process\/performance management<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Project\/program and multi-project management<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Corporate controlling<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Global service management of shared service center (SSC) operations<\/span><\/li>\n<\/ul>\n <\/div>[vc_column_text css_animation=&#8221;fadeInDown&#8221;]\n<h3>Andreas Klare &#8211; Professional key facts:<\/h3>\n[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-chevron-right\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"5px\" data-alignment=\"left\"> \n<ul>\n<li><span style=\"font-size: 14pt;\">Since 2021 Sole Proprietor and Managing Director of Klare Solutions GmbH (Business Coaching &amp; Mentoring, Recruitment Consultancy, Projects and Programs)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Since 2019 Systemic Coach with subsequent certifications as Leadership Coach and Team Coach as well as Online Coach (parallel to my job at Global Business Services as per below)<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">2017-2020: Vice President Global Business Services in an international logistics group; Establishing of captive SSCs (Manila\/Bucharest) and Interim Managing Director in Bucharest<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">2013-2016: Head of various strategic projects and transformation programs in operational logistics units (Land Transport, Air\/Ocean).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">2004-2012: Project Manager and Controller at the headquarters of an international logistics group<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">1999-2004: Key Account Manager Contract Logistics in Singapore<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">1996-1999: Trainee and project manager in an international logistics group<\/span><\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#e9e9eb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;2%&#8221; top_padding_phone=&#8221;12%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;12%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeInDown&#8221;]\n<h3>Qualifications:<\/h3>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;1%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>Industrial Engineer<\/h5>\n<p>University Paderborn <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>Systemic Coach &amp; Consultant<\/h5>\n<p>Coach Akademie Schweiz, St. Gallen <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>Systemic Team Coach &amp; Trainer<\/h5>\n<p>Coach Akademie Schweiz, St. Gallen <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>Value-oriented Systemic Leadership Coach<\/h5>\n<p>Coach Akademie Schweiz, St. Gallen <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>CAI Online-Coach<\/h5>\n<p>Karlsruher Institute <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>PERSONALITY PROFILER Coach<\/h5>\n<p>LINC GmbH, L\u00fcneburg <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>HOGAN PERSONALITY ASSESSMENT<\/h5>\n<p>HOGAN ASSESSMENT SYSTEMS INC. (USA) <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>Prince2 Agile &#8211; Practitioner<\/h5>\n<p>ILX, London <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-chevron-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h5>SixSigma Green Belt<\/h5>\n<p>Deutsche Bahn <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;2%&#8221; top_padding_phone=&#8221;9%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<blockquote><p><span style=\"font-size: 14pt;\">In my private life I am a family man, surrounded by female beings: In addition to my wife, who has been by my side since we studied together, these include two \u201cwild teenagers\u201d (our daughter and the cat Lilli) as well as our Croatian mixed-breed dog Kiara. In my free time I enjoy jogging and long forest walks with Kiara in the early morning hours.<\/span><\/p><\/blockquote>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;0&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1624454083587{padding-bottom: 15px !important;}&#8221;]\n<h3><em>You would like to get to know me better? <\/em><\/h3>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;CONTACT&#8221; url=&#8221;https:\/\/businesscoachingonline.de\/en\/contact\/&#8221; css_animation=&#8221;zoomInDown&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;522&#8243; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;skip-lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;16%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;16%&#8221; left_padding_desktop=&#8221;9%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;9%&#8221; top_padding_tablet=&#8221;25%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;25%&#8221; top_padding_phone=&#8221;35%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;35%&#8221; text_color=&#8221;custom&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-282","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/pages\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":23,"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/pages\/282\/revisions"}],"predecessor-version":[{"id":2227,"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/pages\/282\/revisions\/2227"}],"wp:attachment":[{"href":"https:\/\/businesscoachingonline.de\/en\/wp-json\/wp\/v2\/media?parent=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}